{"id":1493,"date":"2024-05-17T10:26:46","date_gmt":"2024-05-17T10:26:46","guid":{"rendered":"https:\/\/www.santacreudesign.com\/?p=1493"},"modified":"2024-05-17T10:34:51","modified_gmt":"2024-05-17T10:34:51","slug":"interiorismo-clinica-dental-beatriz-rubio-03","status":"publish","type":"post","link":"https:\/\/www.santacreudesign.com\/es\/interiorismo-clinica-dental-beatriz-rubio-03\/","title":{"rendered":"Interiorismo Cl\u00ednica dental Beatriz Rubio 03"},"content":{"rendered":"<style>.kb-row-layout-id1493_ac5969-1d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1493_ac5969-1d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1493_ac5969-1d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}.kb-row-layout-id1493_ac5969-1d > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1493_ac5969-1d > .kt-row-column-wrap{grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1493_ac5969-1d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1493_ac5969-1d alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1493_8622e7-4b > .kt-inside-inner-col,.kadence-column1493_8622e7-4b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1493_8622e7-4b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1493_8622e7-4b > .kt-inside-inner-col{flex-direction:column;}.kadence-column1493_8622e7-4b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1493_8622e7-4b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1493_8622e7-4b{position:relative;}@media all and (max-width: 1024px){.kadence-column1493_8622e7-4b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1493_8622e7-4b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1493_8622e7-4b\"><div class=\"kt-inside-inner-col\">\n<h1 class=\"wp-block-heading\">Interiorismo Cl\u00ednica dental<br>Beatriz Rubio 03<\/h1>\n<\/div><\/div>\n\n\n<style>.kadence-column1493_0d3d57-61 > .kt-inside-inner-col,.kadence-column1493_0d3d57-61 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1493_0d3d57-61 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1493_0d3d57-61 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1493_0d3d57-61 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1493_0d3d57-61 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1493_0d3d57-61{position:relative;}@media all and (max-width: 1024px){.kadence-column1493_0d3d57-61 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1493_0d3d57-61 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1493_0d3d57-61 project_menu\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-text-align-right wp-block-paragraph\"><a href=\"https:\/\/www.santacreudesign.com\/es\/interiorismo-clinicas-dentales\/\">Cl\u00ednicas dentales<\/a><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2018\" src=\"https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_01-scaled.webp\" alt=\"Interiorisme Cl\u00ednica Dental Beatriz Rubio - Hall\" class=\"wp-image-1471\" srcset=\"https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_01-scaled.webp 2560w, https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_01-300x237.webp 300w, https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_01-1024x807.webp 1024w, https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_01-768x606.webp 768w, https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_01-1536x1211.webp 1536w, https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_01-2048x1615.webp 2048w, https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_01-1200x946.webp 1200w, https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_01-1400x1104.webp 1400w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n<style>.kb-row-layout-id1493_892e31-dc > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1493_892e31-dc > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1493_892e31-dc > .kt-row-column-wrap{column-gap:80px;row-gap:var(--global-kb-gap-md, 2rem);max-width:1220px;margin-left:auto;margin-right:auto;padding-top:80px;padding-bottom:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1493_892e31-dc > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1493_892e31-dc > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1493_892e31-dc > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1493_892e31-dc alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1493_96403d-cf > .kt-inside-inner-col,.kadence-column1493_96403d-cf > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1493_96403d-cf > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1493_96403d-cf > .kt-inside-inner-col{flex-direction:column;}.kadence-column1493_96403d-cf > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1493_96403d-cf > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1493_96403d-cf{position:relative;}@media all and (max-width: 1024px){.kadence-column1493_96403d-cf > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1493_96403d-cf > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1493_96403d-cf\"><div class=\"kt-inside-inner-col\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a571df42beec&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a571df42beec\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1144\" height=\"1590\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_02.webp\" alt=\"Interiorisme Cl\u00ednica Dental Beatriz Rubio - Passad\u00eds despatx\" class=\"wp-image-1478\" srcset=\"https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_02.webp 1144w, https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_02-216x300.webp 216w, https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_02-737x1024.webp 737w, https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_02-768x1067.webp 768w, https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_02-1105x1536.webp 1105w, https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_02-300x417.webp 300w\" sizes=\"auto, (max-width: 1144px) 100vw, 1144px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column1493_e7e4e3-8a > .kt-inside-inner-col,.kadence-column1493_e7e4e3-8a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1493_e7e4e3-8a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1493_e7e4e3-8a > .kt-inside-inner-col{flex-direction:column;}.kadence-column1493_e7e4e3-8a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1493_e7e4e3-8a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1493_e7e4e3-8a{position:relative;}@media all and (max-width: 1024px){.kadence-column1493_e7e4e3-8a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1493_e7e4e3-8a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1493_e7e4e3-8a\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading\">Descripci\u00f3n del proyecto<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Proyecto de reforma interior de una cl\u00ednica dental en Cerdanyola del Vall\u00e8s. El objetico principal del proyecto era modernizar y conseguir mayor amplitud en toda la cl\u00ednica. Por ese motivo realizamos todos los cerramientos posibles en cristal desdibujando as\u00ed los l\u00edmites de los espacios y dando la tan buscada sensaci\u00f3n de amplitud y transparencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Introducimos la madera de roble natural como elemento diferenciador a la vez que a\u00f1adimos al espacio un ambiente mas c\u00e1lido y cercano al paciente. Este acabado se repite en los frontales de los muebles cl\u00ednicos y en espacios que requieren de mas privacidad como por ejemplo la sala de RX y el ba\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de respetar y aprovechar la entrada de luz exterior, utilizamos unas luminarias circulares de 1,2m de di\u00e1metro empotradas en el techo sobre cada sill\u00f3n dental aportando al ambiente sensaci\u00f3n de amplitud y tranquilidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cl\u00ednica resultante est\u00e1 compuesta por cinco box dentales, un ortopanto, una sala de esterilizaci\u00f3n, un despacho y un office. Cada estancia y sobretodo los box est\u00e1n se\u00f1alizados con el n\u00famero opaco en la puerta. Esto genera un juego de contraste entre luz y sombra muy atractivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este proyecto fue ejecutado como obra \u201cllave en mano\u201d contando con la colaboraci\u00f3n de industriales altamente calificados.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1493_8efb5f-a2 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1493_8efb5f-a2 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1493_8efb5f-a2 > .kt-row-column-wrap{column-gap:80px;row-gap:var(--global-kb-gap-md, 2rem);max-width:1220px;margin-left:auto;margin-right:auto;padding-top:80px;padding-bottom:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1493_8efb5f-a2 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1493_8efb5f-a2 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1493_8efb5f-a2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1493_8efb5f-a2 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1493_147135-71 > .kt-inside-inner-col,.kadence-column1493_147135-71 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1493_147135-71 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1493_147135-71 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1493_147135-71 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1493_147135-71 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1493_147135-71{position:relative;}@media all and (max-width: 1024px){.kadence-column1493_147135-71 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1493_147135-71 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1493_147135-71\"><div class=\"kt-inside-inner-col\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a571df42d28d&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a571df42d28d\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1144\" height=\"1590\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_04.webp\" alt=\"Interiorisme Cl\u00ednica Dental Beatriz Rubio - Passad\u00eds\" class=\"wp-image-1485\" srcset=\"https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_04.webp 1144w, https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_04-216x300.webp 216w, https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_04-737x1024.webp 737w, https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_04-768x1067.webp 768w, https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_04-1105x1536.webp 1105w, https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_04-300x417.webp 300w\" sizes=\"auto, (max-width: 1144px) 100vw, 1144px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column1493_09c22f-40 > .kt-inside-inner-col,.kadence-column1493_09c22f-40 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1493_09c22f-40 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1493_09c22f-40 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1493_09c22f-40 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1493_09c22f-40 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1493_09c22f-40{position:relative;}@media all and (max-width: 1024px){.kadence-column1493_09c22f-40 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1493_09c22f-40 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1493_09c22f-40\"><div class=\"kt-inside-inner-col\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a571df42dace&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a571df42dace\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1144\" height=\"1590\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_05.webp\" alt=\"Interiorisme Cl\u00ednica Dental Beatriz Rubio - Box\" class=\"wp-image-1489\" srcset=\"https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_05.webp 1144w, https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_05-216x300.webp 216w, https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_05-737x1024.webp 737w, https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_05-768x1067.webp 768w, https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_05-1105x1536.webp 1105w, https:\/\/www.santacreudesign.com\/wp-content\/uploads\/2024\/05\/santacreu_projecte_clinicadental_beatriz_rubio_03_05-300x417.webp 300w\" sizes=\"auto, (max-width: 1144px) 100vw, 1144px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Proyecto de reforma interior de una cl\u00ednica dental en Cerdanyola del Vall\u00e8s.<\/p>\n","protected":false},"author":1,"featured_media":1476,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[23,24],"tags":[],"class_list":["post-1493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proyectos","category-clinicas-dentales","with-featured-image"],"_links":{"self":[{"href":"https:\/\/www.santacreudesign.com\/es\/wp-json\/wp\/v2\/posts\/1493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.santacreudesign.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.santacreudesign.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.santacreudesign.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.santacreudesign.com\/es\/wp-json\/wp\/v2\/comments?post=1493"}],"version-history":[{"count":2,"href":"https:\/\/www.santacreudesign.com\/es\/wp-json\/wp\/v2\/posts\/1493\/revisions"}],"predecessor-version":[{"id":1495,"href":"https:\/\/www.santacreudesign.com\/es\/wp-json\/wp\/v2\/posts\/1493\/revisions\/1495"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.santacreudesign.com\/es\/wp-json\/wp\/v2\/media\/1476"}],"wp:attachment":[{"href":"https:\/\/www.santacreudesign.com\/es\/wp-json\/wp\/v2\/media?parent=1493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.santacreudesign.com\/es\/wp-json\/wp\/v2\/categories?post=1493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.santacreudesign.com\/es\/wp-json\/wp\/v2\/tags?post=1493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}